{"id":787,"date":"2021-01-03T18:13:34","date_gmt":"2021-01-03T18:13:34","guid":{"rendered":"http:\/\/tedxalcarriast.com\/?page_id=787"},"modified":"2021-01-07T19:17:04","modified_gmt":"2021-01-07T19:17:04","slug":"que-es-ted","status":"publish","type":"page","link":"https:\/\/tedxalcarriast.com\/index.php\/que-es-ted\/","title":{"rendered":"\u00bfQu\u00e9 es TED?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"787\" class=\"elementor elementor-787\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1fa892a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1fa892a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2392ba0\" data-id=\"2392ba0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-438bfc3 elementor-widget elementor-widget-image\" data-id=\"438bfc3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.tedxalcarriast.com\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"608\" height=\"136\" src=\"https:\/\/tedxalcarriast.com\/wp-content\/uploads\/2020\/12\/logotedxalcarriast.png\" class=\"attachment-large size-large\" alt=\"Logo de TEDxAlcarriaSt\" srcset=\"https:\/\/tedxalcarriast.com\/wp-content\/uploads\/2020\/12\/logotedxalcarriast.png 608w, https:\/\/tedxalcarriast.com\/wp-content\/uploads\/2020\/12\/logotedxalcarriast-300x67.png 300w\" sizes=\"auto, (max-width: 608px) 100vw, 608px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3f65e6d\" data-id=\"3f65e6d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb30fcc hfe-nav-menu__align-right hfe-submenu-icon-arrow hfe-submenu-animation-none hfe-link-redirect-child hfe-nav-menu__breakpoint-tablet elementor-widget elementor-widget-navigation-menu\" data-id=\"bb30fcc\" data-element_type=\"widget\" data-widget_type=\"navigation-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"hfe-nav-menu hfe-layout-horizontal hfe-nav-menu-layout horizontal hfe-pointer__underline hfe-animation__fade\" data-layout=\"horizontal\">\n\t\t\t\t<div class=\"hfe-nav-menu__toggle elementor-clickable\">\n\t\t\t\t\t<div class=\"hfe-nav-menu-icon\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" tabindex=\"0\" class=\"fas fa-align-justify\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<nav class=\"hfe-nav-menu__layout-horizontal hfe-nav-menu__submenu-arrow\" data-toggle-icon=\"&lt;i aria-hidden=&quot;true&quot; tabindex=&quot;0&quot; class=&quot;fas fa-align-justify&quot;&gt;&lt;\/i&gt;\" data-close-icon=\"&lt;i aria-hidden=&quot;true&quot; tabindex=&quot;0&quot; class=&quot;far fa-window-close&quot;&gt;&lt;\/i&gt;\" data-full-width=\"yes\"><ul id=\"menu-1-bb30fcc\" class=\"hfe-nav-menu\"><li id=\"menu-item-924\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children parent hfe-has-submenu hfe-creative-menu\"><div class=\"hfe-has-submenu-container\"><a href=\"#\" class = \"hfe-menu-item\">Ponentes<span class='hfe-menu-toggle sub-arrow hfe-menu-child-0'><i class='fa'><\/i><\/span><\/a><\/div>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-2170\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/ponentes-2025\/\" class = \"hfe-sub-menu-item\">Ponentes 2025<\/a><\/li>\n\t<li id=\"menu-item-2027\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/ponentes-2024\/\" class = \"hfe-sub-menu-item\">Ponentes 2024<\/a><\/li>\n\t<li id=\"menu-item-1787\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/ponentes-2023\/\" class = \"hfe-sub-menu-item\">Ponentes 2023<\/a><\/li>\n\t<li id=\"menu-item-1596\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/ponentes-2022\/\" class = \"hfe-sub-menu-item\">Ponentes 2022<\/a><\/li>\n\t<li id=\"menu-item-509\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/ponentes-2020\/\" class = \"hfe-sub-menu-item\">Ponentes 2020<\/a><\/li>\n\t<li id=\"menu-item-679\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/ponentes-2018\/\" class = \"hfe-sub-menu-item\">Ponentes 2018<\/a><\/li>\n\t<li id=\"menu-item-678\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/ponentes-2017\/\" class = \"hfe-sub-menu-item\">Ponentes 2017<\/a><\/li>\n\t<li id=\"menu-item-677\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/ponentes-2016\/\" class = \"hfe-sub-menu-item\">Ponentes 2016<\/a><\/li>\n\t<li id=\"menu-item-676\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/ponentes-2015\/\" class = \"hfe-sub-menu-item\">Ponentes 2015<\/a><\/li>\n\t<li id=\"menu-item-680\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/ponentes-2014\/\" class = \"hfe-sub-menu-item\">Ponentes 2014<\/a><\/li>\n\t<li id=\"menu-item-675\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/ponentes-2013\/\" class = \"hfe-sub-menu-item\">Ponentes 2013<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-786\" class=\"unclickable menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children parent hfe-has-submenu hfe-creative-menu\"><div class=\"hfe-has-submenu-container\"><a href=\"#\" class = \"hfe-menu-item\">Eventos<span class='hfe-menu-toggle sub-arrow hfe-menu-child-0'><i class='fa'><\/i><\/span><\/a><\/div>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-2217\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/reaccionar\/\" class = \"hfe-sub-menu-item\">Evento 2025<\/a><\/li>\n\t<li id=\"menu-item-2121\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/recomenzar\/\" class = \"hfe-sub-menu-item\">Evento 2024<\/a><\/li>\n\t<li id=\"menu-item-1946\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/contrapunto\/\" class = \"hfe-sub-menu-item\">Evento 2023<\/a><\/li>\n\t<li id=\"menu-item-1687\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/enredados\/\" class = \"hfe-sub-menu-item\">Evento 2022<\/a><\/li>\n\t<li id=\"menu-item-139\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/oportunidad\/\" class = \"hfe-sub-menu-item\">Evento 2020<\/a><\/li>\n\t<li id=\"menu-item-227\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/desobedienciainteligente\/\" class = \"hfe-sub-menu-item\">Evento 2018<\/a><\/li>\n\t<li id=\"menu-item-226\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/deconstrucciones\/\" class = \"hfe-sub-menu-item\">Evento 2017<\/a><\/li>\n\t<li id=\"menu-item-225\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/solucioneslocalesretosglobales\/\" class = \"hfe-sub-menu-item\">Evento 2016<\/a><\/li>\n\t<li id=\"menu-item-224\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/innovacioncontradicion\/\" class = \"hfe-sub-menu-item\">Evento 2015<\/a><\/li>\n\t<li id=\"menu-item-223\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/explorandoloslimitesdelconocimiento\/\" class = \"hfe-sub-menu-item\">Evento 2014<\/a><\/li>\n\t<li id=\"menu-item-222\" class=\"menu-item menu-item-type-post_type menu-item-object-page hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/despertandoeltalentolocal\/\" class = \"hfe-sub-menu-item\">Evento 2013<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-22\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/equipo\/\" class = \"hfe-menu-item\">Equipo<\/a><\/li>\n<li id=\"menu-item-23\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/patrocinador\/\" class = \"hfe-menu-item\">Patrocinadores<\/a><\/li>\n<li id=\"menu-item-806\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/que-es-ted\/\" class = \"hfe-menu-item\">\u00bfQu\u00e9 es TED?<\/a><\/li>\n<li id=\"menu-item-807\" class=\"menu-item menu-item-type-post_type menu-item-object-page parent hfe-creative-menu\"><a href=\"https:\/\/tedxalcarriast.com\/index.php\/que-es-tedxalcarriast\/\" class = \"hfe-menu-item\">Sobre TEDxAlcarriaSt<\/a><\/li>\n<\/ul><\/nav>              \n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb3097d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb3097d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32559e8\" data-id=\"32559e8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-337c0b2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"337c0b2\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-92073f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92073f2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8c9cdb2\" data-id=\"8c9cdb2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-00c68e3 elementor-widget elementor-widget-text-editor\" data-id=\"00c68e3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><h3 style=\"text-align: justify;\">\u00bfQu\u00e9 es TED y TEDx?<\/h3><p style=\"text-align: justify;\">TED es una organizaci\u00f3n sin \u00e1nimo de lucro dedicada a las Ideas que Merecen la pena Difundir (\u201c<em>Ideas Worth Spreading<\/em>\u201c). Comenz\u00f3 como una conferencia de 4 d\u00edas de duraci\u00f3n celebrada en California, hace 25 a\u00f1os y ha crecido para dar apoyo mediante diversas iniciativas a esas ideas que pueden cambiar el mundo. La conferencia TED anual invita a pensadores y profesionales de todo el mundo a hablar durante 18 minutos. Sus charlas se ofrecen m\u00e1s tarde libre y gratuitamente en TED.com. Entre los ponentes de TED se encuentran Bill Gates, Al Gore, Jane Goodall, Elizabeth Gilbert, Sir Richard Branson, Nandan Nilekani, Philippe Starck, Ngozi Okonjo-Iweala, Isabel Allende y el Gordon Brown, Primer Ministro del Reino Unido. La conferencia anual de TED tiene lugar en Long Beach, California, con retransmisi\u00f3n simult\u00e1nea (\u201c<em>simulcast<\/em>\u201c) en Palm Springs.; TEDGlobal se celebra cada a\u00f1o en Edimburgo, Escocia (anteriormente se celebraba en Oxford, Reino Unido). Las iniciativas de TED en los medios incluyen TED.com, donde cada d\u00eda se ofrecen nuevas TEDTalks, y Open Translation Project, que ofrece subt\u00edtulos y transcripciones interactivas as\u00ed como la posibilidad de que voluntarios de todo el mundo puedan traducir cualquier TEDTalk que les interese. TED ha establecido el premio anual TED Prize, concedido a individuos excelentes que desean cambiar el mundo y a los que se les ofrece la oportunidad de llevar a la pr\u00e1ctica sus deseos; TEDx, que son eventos independientes similares a TED celebrados en todo el mundo; y el programa TEDFellows,que posibilita que aquellos innovadores que est\u00e1n cambiando el mundo desde cualquier lugar pasen a formar parte de la comunidad TED y, con su ayuda, amplificar el impacto de sus ya admirables proyectos y actividades.<\/p><p style=\"text-align: justify;\">Se puede estar informado sobre TED en Twitter, en\u00a0<a href=\"http:\/\/twitter.com\/TEDTalks\">twitter.com\/TEDTalks<\/a>, o en Facebook, en\u00a0<a href=\"http:\/\/facebook.com\/TED\">facebook.com\/TED<\/a>.<\/p><header class=\"entry-header\"><\/header><div class=\"entry-content\"><h3 style=\"text-align: justify;\">\u00bfQu\u00e9 es TEDx, x = independently organized event?<\/h3><p style=\"text-align: justify;\">En el esp\u00edritu de las ideas que merece la pena difundir, TEDx es un programa de eventos locales y auto-organizados que re\u00fanen a personas interesadas en compartir una experiencia similar a TED. En un evento TEDx, v\u00eddeos de TEDTalks y ponentes en vivo se combinan para provocar la discusi\u00f3n en profundidad y la conexi\u00f3n en peque\u00f1os grupos entre los asistentes. Estos eventos locales y auto-organizados se denominan TEDx, siendo x equivalente a evento TED organizado de modo independiente. TED Conference ofrece un conjunto gen\u00e9rico de gu\u00edas para el programa TEDx, pero cada evento TEDx individual se organiza por s\u00ed mismo (sometido a determinadas reglas y normas).<\/p><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-234ceb0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"234ceb0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71750cc\" data-id=\"71750cc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6d133d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f6d133d\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f739c2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f739c2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61c2b03\" data-id=\"61c2b03\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de979a6 elementor-widget elementor-widget-text-editor\" data-id=\"de979a6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><h3 style=\"text-align: justify;\">About TED<\/h3><p style=\"text-align: justify;\">TED is a nonprofit organization devoted to Ideas Worth Spreading. Started as a four-day conference in California 25 years ago, TED has grown to support those world-changing ideas with multiple initiatives. The annual TED Conference invites the world\u2019s leading thinkers and doers to speak for 18 minutes. Their talks are then made available, free, at TED.com. TED speakers have included Bill Gates, Al Gore, Jane Goodall, Elizabeth Gilbert, Sir Richard Branson, Nandan Nilekani, Philippe Starck, Ngozi Okonjo-Iweala, Isabel Allende and UK Prime Minister Gordon Brown. The annual TED Conference takes place in Long Beach, California, with simulcast in Palm Springs; TEDGlobal is held each year in Oxford, UK. TED\u2019s media initiatives include TED.com, where new TEDTalks are posted daily, and the Open Translation Project, which provides subtitles and interactive transcripts as well as the ability for any TEDTalk to be translated by volunteers worldwide. TED has established the annual TED Prize, where exceptional individuals with a wish to change the world are given the opportunity to put their wishes into action; TEDx, which offers individuals or groups a way to organize local, independent TED-like events around the world; and the TEDFellows program, helping world-changing innovators from around the globe to become part of the TED community and, with its help, amplify the impact of their remarkable projects and activities.<\/p><p style=\"text-align: justify;\">Follow TED on Twitter at\u00a0<a href=\"http:\/\/twitter.com\/TEDTalks\">twitter.com\/TEDTalks<\/a>, or on Facebook at\u00a0<a href=\"http:\/\/facebook.com\/TED\">facebook.com\/TED<\/a>.<\/p><h3 style=\"text-align: justify;\">About TEDx, x = independently organized event<\/h3><p style=\"text-align: justify;\">In the spirit of ideas worth spreading, TEDx is a program of local, self-organized events that bring people together to share a TED-like experience. At a TEDx event, TEDTalks video and live speakers combine to spark deep discussion and connection in a small group. These local, self-organized events are branded TEDx, where x = independently organized TED event. The TED Conference provides general guidance for the TEDx program, but individual TEDx events are self-organized. (Subject to certain rules and regulations.)<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f4457e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f4457e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9612720\" data-id=\"9612720\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5411b80 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5411b80\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-de620a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"de620a9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e6f0c8d\" data-id=\"e6f0c8d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7d0420 elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"f7d0420\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-d2c296a\" href=\"https:\/\/www.facebook.com\/TEDxAlcarria\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-8459bb9\" href=\"https:\/\/twitter.com\/TEDxAlcarriaSt\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-2cd93ef\" href=\"https:\/\/www.youtube.com\/channel\/UCxiVwEkHUpAOCF_2Zz2kw9g\/featured\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-flickr elementor-repeater-item-c200eb8\" href=\"https:\/\/www.flickr.com\/photos\/tedxalcarriast\/albums\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Flickr<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-flickr\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f1d5459\" data-id=\"f1d5459\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef08e3c elementor-widget elementor-widget-text-editor\" data-id=\"ef08e3c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><p><a href=\"http:\/\/creativecommons.org\/licenses\/by-nc\/4.0\/\" rel=\"license\"><img decoding=\"async\" style=\"border-width: 0;\" src=\"https:\/\/i.creativecommons.org\/l\/by-nc\/4.0\/80x15.png\" alt=\"Licencia Creative Commons\" \/><\/a><br \/><a href=\"http:\/\/creativecommons.org\/licenses\/by-nc\/4.0\/\" rel=\"license\">Licencia Creative Commons Atribuci\u00f3n-NoComercial 4.0 Internacional<\/a>.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ea5a33f\" data-id=\"ea5a33f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ada1f7 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5ada1f7\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/tedxalcarriast.com\/index.php\/formulario-de-contacto\/\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Contacta con nosotros<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cce4bda elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cce4bda\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2bc69b0\" data-id=\"2bc69b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbf4c70 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cbf4c70\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d99f747 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d99f747\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b9d01b\" data-id=\"2b9d01b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6adaa4a elementor-widget elementor-widget-text-editor\" data-id=\"6adaa4a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><p><strong>Este evento independiente TEDx se realiza bajo licencia de TED<\/strong><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ponentes Ponentes 2021 Ponentes 2020 Ponentes 2018 Ponentes 2017 Ponentes 2016 Ponentes 2015 Ponentes 2014 Ponentes 2013 Eventos Evento 2020 Evento 2018 Evento 2017 Evento 2016 Evento 2015 Evento 2014 Evento 2013 Equipo Patrocinadores \u00bfQu\u00e9 es TED? Sobre TEDxAlcarriaSt \u00bfQu\u00e9 es TED y TEDx? TED es una organizaci\u00f3n sin \u00e1nimo de lucro dedicada a las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-787","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 es TED? - tedxalcarriast.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tedxalcarriast.com\/index.php\/que-es-ted\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es TED? - tedxalcarriast.com\" \/>\n<meta property=\"og:description\" content=\"Ponentes Ponentes 2021 Ponentes 2020 Ponentes 2018 Ponentes 2017 Ponentes 2016 Ponentes 2015 Ponentes 2014 Ponentes 2013 Eventos Evento 2020 Evento 2018 Evento 2017 Evento 2016 Evento 2015 Evento 2014 Evento 2013 Equipo Patrocinadores \u00bfQu\u00e9 es TED? Sobre TEDxAlcarriaSt \u00bfQu\u00e9 es TED y TEDx? TED es una organizaci\u00f3n sin \u00e1nimo de lucro dedicada a las [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tedxalcarriast.com\/index.php\/que-es-ted\/\" \/>\n<meta property=\"og:site_name\" content=\"tedxalcarriast.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TEDxAlcarria\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-07T19:17:04+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/tedxalcarriast.com\/wp-content\/uploads\/2020\/12\/logotedxalcarriast.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TEDxAlcarriaSt\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"3 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/tedxalcarriast.com\/#organization\",\"name\":\"TEDxAlcarriaSt\",\"url\":\"https:\/\/tedxalcarriast.com\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/TEDxAlcarria\",\"https:\/\/www.youtube.com\/channel\/UCxiVwEkHUpAOCF_2Zz2kw9g\/featured\",\"https:\/\/twitter.com\/TEDxAlcarriaSt\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/tedxalcarriast.com\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/tedxalcarriast.com\/wp-content\/uploads\/2021\/01\/logo800x600.png\",\"width\":800,\"height\":573,\"caption\":\"TEDxAlcarriaSt\"},\"image\":{\"@id\":\"https:\/\/tedxalcarriast.com\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tedxalcarriast.com\/#website\",\"url\":\"https:\/\/tedxalcarriast.com\/\",\"name\":\"tedxalcarriast.com\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/tedxalcarriast.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/tedxalcarriast.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/tedxalcarriast.com\/index.php\/que-es-ted\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"http:\/\/tedxalcarriast.com\/wp-content\/uploads\/2020\/12\/logotedxalcarriast.png\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tedxalcarriast.com\/index.php\/que-es-ted\/#webpage\",\"url\":\"https:\/\/tedxalcarriast.com\/index.php\/que-es-ted\/\",\"name\":\"\\u00bfQu\\u00e9 es TED? - tedxalcarriast.com\",\"isPartOf\":{\"@id\":\"https:\/\/tedxalcarriast.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tedxalcarriast.com\/index.php\/que-es-ted\/#primaryimage\"},\"datePublished\":\"2021-01-03T18:13:34+00:00\",\"dateModified\":\"2021-01-07T19:17:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tedxalcarriast.com\/index.php\/que-es-ted\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tedxalcarriast.com\/index.php\/que-es-ted\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tedxalcarriast.com\/index.php\/que-es-ted\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tedxalcarriast.com\/\",\"url\":\"https:\/\/tedxalcarriast.com\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tedxalcarriast.com\/index.php\/que-es-ted\/\",\"url\":\"https:\/\/tedxalcarriast.com\/index.php\/que-es-ted\/\",\"name\":\"\\u00bfQu\\u00e9 es TED?\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/tedxalcarriast.com\/index.php\/wp-json\/wp\/v2\/pages\/787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tedxalcarriast.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tedxalcarriast.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tedxalcarriast.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tedxalcarriast.com\/index.php\/wp-json\/wp\/v2\/comments?post=787"}],"version-history":[{"count":31,"href":"https:\/\/tedxalcarriast.com\/index.php\/wp-json\/wp\/v2\/pages\/787\/revisions"}],"predecessor-version":[{"id":1347,"href":"https:\/\/tedxalcarriast.com\/index.php\/wp-json\/wp\/v2\/pages\/787\/revisions\/1347"}],"wp:attachment":[{"href":"https:\/\/tedxalcarriast.com\/index.php\/wp-json\/wp\/v2\/media?parent=787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}